{"id":144,"count":1,"description":"","link":"https:\/\/okularymarket.pl\/en\/tag\/sprzedaz-okularow-w-sklepie\/","name":"sprzeda\u017c okular\u00f3w w sklepie","slug":"sprzedaz-okularow-w-sklepie","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/okularymarket.pl\/en\/wp-json\/wp\/v2\/tags\/144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/okularymarket.pl\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/okularymarket.pl\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/okularymarket.pl\/en\/wp-json\/wp\/v2\/posts?tags=144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}